{"id":1521,"date":"2023-10-09T17:21:51","date_gmt":"2023-10-09T17:21:51","guid":{"rendered":"https:\/\/atlantiqueassurances.bj\/?p=1521"},"modified":"2023-12-09T18:16:26","modified_gmt":"2023-12-09T18:16:26","slug":"atlantique-assurances-benin-iardt-sassocie-a-la-protectrice-assurances-pour-la-couverture-des-risques-speciaux-au-benin","status":"publish","type":"post","link":"https:\/\/afgassurances.bj\/iardt\/atlantique-assurances-benin-iardt-sassocie-a-la-protectrice-assurances-pour-la-couverture-des-risques-speciaux-au-benin\/","title":{"rendered":"Atlantique Assurances B\u00e9nin IARDT s&rsquo;associe \u00e0 La Protectrice Assurances pour la couverture des Risques Sp\u00e9ciaux au B\u00e9nin"},"content":{"rendered":"<p>Le 6 octobre 2023, une \u00e9tape significative dans le secteur de l&rsquo;assurance au B\u00e9nin a \u00e9t\u00e9 c\u00e9l\u00e9br\u00e9e avec \u00e9clat au Novotel de Cotonou. Cet \u00e9v\u00e9nement m\u00e9morable a marqu\u00e9 le lancement de nouvelles extensions de garanties d\u00e9di\u00e9es \u00e0 la couverture des Risques Sp\u00e9ciaux, issues d&rsquo;une collaboration fructueuse entre deux acteurs majeurs du domaine : La Protectrice Assurances et Atlantique Assurances B\u00e9nin IARDT.<\/p>\n<p>L&rsquo;atmosph\u00e8re \u00e9tait \u00e9tait conviviale avec la pr\u00e9sence des dirigeants de ces deux entreprises<\/p>\n<p>, des cadres sup\u00e9rieurs d&rsquo;entreprises, des futurs assur\u00e9s, ainsi que des \u00e9minents repr\u00e9sentants du secteur de l&rsquo;assurance. L&rsquo;\u00e9v\u00e9nement a \u00e9t\u00e9 inaugur\u00e9 par un discours d&rsquo;ouverture vibrant du Pr\u00e9sident Directeur G\u00e9n\u00e9ral de La Protectrice Assurances, Monsieur Jos\u00e9 Kwassi SYMENOUH.<\/p>\n<p>Ensuite, les messieurs Ez\u00e9chiel SYMENOUH et Pascal SILIADIN ont eu l&rsquo;honneur de d\u00e9voiler et d&rsquo;exposer en d\u00e9tail les trois nouvelles extensions de garanties sp\u00e9ciales, \u00e0 savoir : les Risques de Responsabilit\u00e9s des Dirigeants, les Risques Cyber et les Risques Politiques. Ces innovations promettent de red\u00e9finir les normes de couverture en mati\u00e8re d&rsquo;assurance.<\/p>\n<p>Madame Florence AYIVI-ELEGBEDE, Directrice G\u00e9n\u00e9rale d&rsquo;Atlantique Assurances IARDT B\u00e9nin, a \u00e9galement pris la parole pour exprimer sa gratitude envers les participants et mettre en exergue l&rsquo;importance cruciale de ce partenariat pour le secteur de l&rsquo;assurance au B\u00e9nin. Elle a soulign\u00e9 l&rsquo;engagement in\u00e9branlable des deux entreprises \u00e0 fournir le soutien n\u00e9cessaire \u00e0 leurs clients.<\/p>\n<p><img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-1538\" src=\"http:\/\/atlantiqueassurances.bj\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-09-at-18.07.50-700x467.jpeg\" alt=\"\" width=\"474\" height=\"316\" srcset=\"https:\/\/afgassurances.bj\/iardt\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-09-at-18.07.50-700x467.jpeg 700w, https:\/\/afgassurances.bj\/iardt\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-09-at-18.07.50-1000x667.jpeg 1000w, https:\/\/afgassurances.bj\/iardt\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-09-at-18.07.50-232x155.jpeg 232w, https:\/\/afgassurances.bj\/iardt\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-09-at-18.07.50-768x512.jpeg 768w, https:\/\/afgassurances.bj\/iardt\/wp-content\/uploads\/2023\/12\/WhatsApp-Image-2023-12-09-at-18.07.50.jpeg 1080w\" sizes=\"(max-width: 474px) 100vw, 474px\" \/><\/p>\n<p>La c\u00e9r\u00e9monie, empreinte de convivialit\u00e9 et de chaleur, s&rsquo;est achev\u00e9e par une s\u00e9ance photo m\u00e9morable, suivie d&rsquo;un somptueux cocktail d\u00eenatoire. Ce dernier a offert aux invit\u00e9s l&rsquo;occasion d&rsquo;\u00e9changer et de c\u00e9l\u00e9brer collectivement cette nouvelle \u00e9tape marquante dans le paysage de l&rsquo;assurance au B\u00e9nin.<\/p>\n<p><iframe title=\"SOIREE DE LANCEMENT DES NOUVELLES EXTENSIONS DE GARANTIES, LES RISQUES SPECIAUX\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/Pxm6h6x1Mg4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>","protected":false},"excerpt":{"rendered":"<p>Le 6 octobre 2023, une \u00e9tape significative dans le secteur de l&rsquo;assurance au B\u00e9nin a \u00e9t\u00e9 c\u00e9l\u00e9br\u00e9e avec \u00e9clat au Novotel de Cotonou. Cet \u00e9v\u00e9nement m\u00e9morable a marqu\u00e9 le lancement de nouvelles extensions de garanties d\u00e9di\u00e9es \u00e0 la couverture des Risques Sp\u00e9ciaux, issues d&rsquo;une collaboration fructueuse entre deux acteurs majeurs du domaine : La Protectrice [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":1530,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5],"tags":[21,20],"class_list":["post-1521","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","tag-partenariats","tag-risques-speciaux"],"acf":[],"views":2056,"_links":{"self":[{"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/posts\/1521","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/comments?post=1521"}],"version-history":[{"count":6,"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/posts\/1521\/revisions"}],"predecessor-version":[{"id":1544,"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/posts\/1521\/revisions\/1544"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/media\/1530"}],"wp:attachment":[{"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/media?parent=1521"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/categories?post=1521"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/tags?post=1521"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}