{"id":1466,"date":"2023-12-01T08:01:24","date_gmt":"2023-12-01T08:01:24","guid":{"rendered":"http:\/\/localhost\/benin-iardt\/?p=1466"},"modified":"2023-12-04T06:48:59","modified_gmt":"2023-12-04T06:48:59","slug":"assurance-globale-banque","status":"publish","type":"post","link":"https:\/\/afgassurances.bj\/iardt\/assurance-globale-banque\/","title":{"rendered":"Assurance globale banque"},"content":{"rendered":"<p><em>Le contrat qui s\u00e9curise votre relation avec votre banque.<\/em><\/p>\n<p>L\u2019assurance Globale de Banque vous indemnise de la perte p\u00e9cuniaire que vous \u00e9prouvez en tant qu\u2019assur\u00e9 du fait de la d\u00e9t\u00e9rioration, de la destruction ou de la disparition totale ou partielle, (par suite de l\u2019un ou l\u2019autre des \u00ab \u00e9v\u00e9nements assur\u00e9s \u00bb survenus pendant la dur\u00e9e du contrat), des\u00a0 \u00ab valeurs \u00bb lui appartenant ou qui lui ont \u00e9t\u00e9 confi\u00e9es dans le cadre de son activit\u00e9 de banque.<\/p>\n<h3>Les garanties<\/h3>\n<h4>Garanties de base obligatoires<\/h4>\n<ul>\n<li>Tous dommages confondus avec sous limitations (d\u00e9tournement, transport de fonds, biens confi\u00e9s\u2026)<\/li>\n<\/ul>\n<h4><strong>Garanties de base compl\u00e9mentaires<\/strong><\/h4>\n<ul>\n<li>D\u00e9t\u00e9riorations mobili\u00e8res et immobili\u00e8res<\/li>\n<li>Honoraires d\u2019experts<\/li>\n<\/ul>\n<h3>Qui peut souscrire ?<\/h3>\n<p>Utilisateurs de services bancaires.<\/p>\n<p>Rejoignez-nous d\u00e8s maintenant pour profiter de tous les avantages r\u00e9serv\u00e9s \u00e0 nos clients particuliers.<\/p>","protected":false},"excerpt":{"rendered":"<p>Le contrat qui s\u00e9curise votre relation avec votre banque. L\u2019assurance Globale de Banque vous indemnise de la perte p\u00e9cuniaire que vous \u00e9prouvez en tant qu\u2019assur\u00e9 du fait de la d\u00e9t\u00e9rioration, de la destruction ou de la disparition totale ou partielle, (par suite de l\u2019un ou l\u2019autre des \u00ab \u00e9v\u00e9nements assur\u00e9s \u00bb survenus pendant la dur\u00e9e [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1467,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-1466","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-particuliers"],"acf":[],"views":3055,"_links":{"self":[{"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/posts\/1466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/comments?post=1466"}],"version-history":[{"count":1,"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/posts\/1466\/revisions"}],"predecessor-version":[{"id":1468,"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/posts\/1466\/revisions\/1468"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/media\/1467"}],"wp:attachment":[{"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/media?parent=1466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/categories?post=1466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/tags?post=1466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}