{"id":1446,"date":"2023-11-30T16:50:42","date_gmt":"2023-11-30T16:50:42","guid":{"rendered":"http:\/\/localhost\/benin-iardt\/?p=1446"},"modified":"2024-10-10T13:02:03","modified_gmt":"2024-10-10T12:02:03","slug":"assurance-auto","status":"publish","type":"post","link":"https:\/\/afgassurances.bj\/iardt\/assurance-auto\/","title":{"rendered":"Assurance auto"},"content":{"rendered":"<p>L\u2019Assurance Automobile de AFG Assurances B\u00e9nin IARDT couvre les dommages corporels et mat\u00e9riels que le conducteur d\u2019un v\u00e9hicule assur\u00e9 chez AFG peut causer aux autres usagers de la route et\/ou aux passagers \u00e0 bord de son v\u00e9hicule.<\/p>\n<p>En fonction des garanties souscrites, l\u2019assurance automobile peut \u00e9galement couvrir les dommages mat\u00e9riels subis par le v\u00e9hicule assur\u00e9 et les dommages corporels du conducteur dudit v\u00e9hicule<\/p>\n<h3>Les<strong> Garanties <\/strong><\/h3>\n<ul>\n<li><strong>Responsabilit\u00e9 Civile<\/strong> aussi appel\u00e9e \u00ab <strong>assurance au tiers<\/strong> \u00bb: elle est OBLIGATOIRE et couvre les dommages corporels et mat\u00e9riels caus\u00e9s aux autres usagers de la route et\/ou aux passagers \u00e0 bord de votre v\u00e9hicule.<\/li>\n<\/ul>\n<p>Les garanties compl\u00e9mentaires \u00e0 la responsabilit\u00e9 civile (d\u00e9fense-recours et la protection du conducteur ou \u2018\u2019L\u2019individuelle Chauffeur)<\/p>\n<ul>\n<li><strong>CEDEAO<\/strong>: La Carte Brune assure \u00e0 l\u2019automobiliste la garantie compl\u00e8te d\u2019une indemnisation prompte, \u00e9quitable et imm\u00e9diate pour tout accident qu\u2019il pourrait causer en dehors de son territoire de r\u00e9sidence habituelle. Le d\u00e9tenteur de la Carte est trait\u00e9 exactement comme si la police d\u2019assurance de base \u00e9tait souscrite aupr\u00e8s d\u2019une compagnie se trouvant dans le pays visit\u00e9 ou par lequel il transite. \u00c9tant donn\u00e9 que la Carte Brune est reconnue par les autorit\u00e9s gouvernementales, l\u2019automobiliste est dispens\u00e9 de toute autre formalit\u00e9 relative \u00e0 la garantie contre les risques de la responsabilit\u00e9 civile.<\/li>\n<li><strong>Protection chauffeur<\/strong>: C\u2019est une clause du contrat qui prend en charge les frais li\u00e9s aux blessures\u00a0ou au d\u00e9c\u00e8s du conducteur, lorsqu\u2019il est responsable de l\u2019accident ou qu\u2019aucun tiers n\u2019a \u00e9t\u00e9 identifi\u00e9.<\/li>\n<\/ul>\n<h3>Les Garanties optionnelles (non obligatoires)<\/h3>\n<p>\u00c9tendez votre niveau de couverture gr\u00e2ce aux garanties optionnelles, elles sont facultatives mais peuvent s\u2019av\u00e9rer tr\u00e8s utiles pour s\u00e9curiser et reconstituer votre investissement automobile. Il s\u2019agit des garanties suivantes :<\/p>\n<ul>\n<li><strong>Bris de glace<\/strong>: Elle vous permettra d\u2019\u00eatre couvert et d\u2019avoir une indemnisation en cas de sinistre sur votre pare-brise, votre lunette arri\u00e8re ou encore vos vitres lat\u00e9rales. Dans certains cas, la garantie bris de glace prend \u00e9galement en charge les r\u00e9troviseurs et les phares.<\/li>\n<li><strong>Vol\u00a0<\/strong>: En souscrivant cette garantie, vous serez indemnis\u00e9 en cas de vol de votre v\u00e9hicule. \u00c7a para\u00eet logique mais ce n&rsquo;est pas tout \u00e0 fait aussi simple que \u00e7a en a l&rsquo;air. Car le vol est une notion multi-facette.<\/li>\n<li><strong>Incendie<\/strong>: Elle est une protection facultative utile lorsque le v\u00e9hicule couvert par le contrat d\u2019assurance subit des dommages li\u00e9s \u00e0 un\u00a0incendie\u00a0ou \u00e0 une explosion. Il peut s\u2019agir d\u2019un remplacement lorsque la voiture est enti\u00e8rement d\u00e9truite ou de r\u00e9parations si les d\u00e9g\u00e2ts sont partiels et que le v\u00e9hicule incendi\u00e9 est r\u00e9parable.<\/li>\n<li><strong>Dommages Collision<\/strong>: Cette garantie\u00a0vous prot\u00e8ge en cas de choc avec un\u00a0<strong>tiers identifi\u00e9<\/strong>\u00a0et vous verse une indemnisation pour les\u00a0<strong>dommages mat\u00e9riels<\/strong>\u00a0subis par votre v\u00e9hicule. Cette\u00a0garantie auto\u00a0optionnelle peut s\u2019av\u00e9rer int\u00e9ressante pour les\u00a0<strong>assur\u00e9s au tiers<\/strong>\u00a0car elle \u00e9tend votre couverture en cas d\u2019accident sans trop augmenter le co\u00fbt de votre assurance auto.<\/li>\n<li><strong>Dommages tous accidents commun\u00e9ment appel\u00e9e \u00ab Tous Risques \u00bb<\/strong>: L\u2019assurance tous risques est la plus compl\u00e8te et la plus protectrice des\u00a0formules d\u2019assurance auto.\u00a0Elle <strong>couvre de nombreux types de\u00a0<\/strong><strong>sinistres auto<\/strong>\u00a0: l\u2019accident, le vol de voiture, les incendies, les bris de glace. Une\u00a0formule tr\u00e8s protectrice\u00a0qui nous fait \u00e9viter bien des d\u00e9sagr\u00e9ments financiers\u2009! En effet, alors que\u00a0<strong>l\u2019<\/strong><strong>assurance\u00a0au tiers<\/strong><strong>\u00a0s\u2019arr\u00eate \u00e0 la\u00a0garantie\u00a0<\/strong><strong>responsabilit\u00e9 civile (RC)<\/strong>, les contrats\u00a0tous risques\u00a0affichent un\u00a0<strong>niveau de garanties tr\u00e8s \u00e9lev\u00e9<\/strong>.\u00a0Celles-ci couvrent\u00a0non seulement le conducteur, mais aussi son v\u00e9hicule. La garantie d\u2019une protection maximale<\/li>\n<\/ul>\n<h3>Qui peut souscrire?<\/h3>\n<ul>\n<li>Tout propri\u00e9taire de v\u00e9hicule \u00e0 4 roues (sous r\u00e9serve des limitations d\u2019\u00e2ge du v\u00e9hicule pour certaines garanties)<\/li>\n<\/ul>\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>L\u2019Assurance Automobile de AFG Assurances B\u00e9nin IARDT couvre les dommages corporels et mat\u00e9riels que le conducteur d\u2019un v\u00e9hicule assur\u00e9 chez AFG peut causer aux autres usagers de la route et\/ou aux passagers \u00e0 bord de son v\u00e9hicule. En fonction des garanties souscrites, l\u2019assurance automobile peut \u00e9galement couvrir les dommages mat\u00e9riels subis par le v\u00e9hicule assur\u00e9 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1448,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-1446","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-particuliers"],"acf":[],"views":6056,"_links":{"self":[{"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/posts\/1446","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/comments?post=1446"}],"version-history":[{"count":3,"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/posts\/1446\/revisions"}],"predecessor-version":[{"id":31940,"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/posts\/1446\/revisions\/31940"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/media\/1448"}],"wp:attachment":[{"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/media?parent=1446"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/categories?post=1446"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/afgassurances.bj\/iardt\/wp-json\/wp\/v2\/tags?post=1446"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}